{"id":65078,"date":"2026-02-12T12:16:36","date_gmt":"2026-02-12T12:16:36","guid":{"rendered":"https:\/\/andreopticas.com\/?post_type=product&#038;p=65078"},"modified":"2026-07-15T07:51:51","modified_gmt":"2026-07-15T07:51:51","slug":"c-de-cartier-642-sa-sunglasses-ct0642sa","status":"publish","type":"product","link":"https:\/\/andreopticas.com\/pt\/product\/c-de-cartier-642-sa-sunglasses-ct0642sa\/","title":{"rendered":"\u00d3culos de Sol C de Cartier 642\/SA \u2013 CT0642SA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":65083,"template":"","meta":{"_acf_changed":false},"brand":[383],"face-shape":[215,214,213,216],"frame-shape":[1724],"gender":[{"id":371,"slug":"men","name":"Homem"},{"id":372,"slug":"mulheres","name":"Mulher"}],"material":[377],"product_brand":[],"product_cat":[20],"product_tag":[],"class_list":{"0":"post-65078","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"brand-cartier","7":"face-shape-diamond-face","8":"face-shape-heart-shaped-face","9":"face-shape-oval-face","10":"face-shape-square-face","11":"frame-shape-oval","12":"gender-men","13":"gender-women","14":"material-metal","15":"product_cat-sunglasses","17":"first","18":"instock","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-variable","23":"has-default-attributes","24":"wvs-archive-product-wrapper","25":"rtwpvg-product"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v26.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cartier C de Cartier 642\/SA Sunglasses - CT0642SA | Andr\u00e9 Opticas<\/title>\n<meta name=\"description\" content=\"In stock and ready to ship worldwide. Discover our exclusive curated selection of Cartier glasses, frames, sunglasses, vintage frames and vintage sunglasses at our online store.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andreopticas.com\/pt\/produto\/c-de-cartier-642-sa-sunglasses-ct0642sa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartier C de Cartier 642\/SA Sunglasses - CT0642SA\" \/>\n<meta property=\"og:description\" content=\"In stock and ready to ship worldwide. Discover our exclusive curated selection of Cartier glasses, frames, sunglasses, vintage frames and vintage sunglasses at our online store.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andreopticas.com\/pt\/produto\/c-de-cartier-642-sa-sunglasses-ct0642sa\/\" \/>\n<meta property=\"og:site_name\" content=\"Andr\u00e9 Opticas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/andre.opticas\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T07:51:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/andreopticas.com\/wp-content\/uploads\/2026\/02\/33244890_64898920_1000.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@andreopticas\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilidade\" \/>\n\t<meta name=\"twitter:data1\" content=\"Em stock\" \/>\n<meta property=\"product:brand\" content=\"Cartier\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"CT0642SA\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cartier C de Cartier 642\/SA Sunglasses - CT0642SA | Andr\u00e9 Opticas","description":"Em stock e pronto para enviar para todo o mundo. Descubra a nossa sele\u00e7\u00e3o exclusiva curada de \u00f3culos, arma\u00e7\u00f5es, \u00f3culos de sol, arma\u00e7\u00f5es vintage e \u00f3culos de sol vintage de Cartier na nossa loja online.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andreopticas.com\/pt\/produto\/c-de-cartier-642-sa-sunglasses-ct0642sa\/","og_locale":"pt_PT","og_type":"article","og_title":"Cartier C de Cartier 642\/SA Sunglasses - CT0642SA","og_description":"In stock and ready to ship worldwide. Discover our exclusive curated selection of Cartier glasses, frames, sunglasses, vintage frames and vintage sunglasses at our online store.","og_url":"https:\/\/andreopticas.com\/pt\/produto\/c-de-cartier-642-sa-sunglasses-ct0642sa\/","og_site_name":"Andr\u00e9 Opticas","article_publisher":"https:\/\/www.facebook.com\/andre.opticas","article_modified_time":"2026-07-15T07:51:51+00:00","og_image":[{"width":1000,"height":1334,"url":"https:\/\/andreopticas.com\/wp-content\/uploads\/2026\/02\/33244890_64898920_1000.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@andreopticas","twitter_misc":{"Disponibilidade":"Em stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/andreopticas.com\/product\/c-de-cartier-642-sa-sunglasses-ct0642sa\/","url":"https:\/\/andreopticas.com\/product\/c-de-cartier-642-sa-sunglasses-ct0642sa\/","name":"Cartier C de Cartier 642\/SA Sunglasses - CT0642SA | Andr\u00e9 Opticas","isPartOf":{"@id":"https:\/\/andreopticas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/andreopticas.com\/product\/c-de-cartier-642-sa-sunglasses-ct0642sa\/#primaryimage"},"image":{"@id":"https:\/\/andreopticas.com\/product\/c-de-cartier-642-sa-sunglasses-ct0642sa\/#primaryimage"},"thumbnailUrl":"https:\/\/andreopticas.com\/wp-content\/uploads\/2026\/02\/33244890_64898920_1000.png","datePublished":"2026-02-12T12:16:36+00:00","dateModified":"2026-07-15T07:51:51+00:00","description":"Em stock e pronto para enviar para todo o mundo. Descubra a nossa sele\u00e7\u00e3o exclusiva curada de \u00f3culos, arma\u00e7\u00f5es, \u00f3culos de sol, arma\u00e7\u00f5es vintage e \u00f3culos de sol vintage de Cartier na nossa loja online.","breadcrumb":{"@id":"https:\/\/andreopticas.com\/product\/c-de-cartier-642-sa-sunglasses-ct0642sa\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/andreopticas.com\/product\/c-de-cartier-642-sa-sunglasses-ct0642sa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/andreopticas.com\/product\/c-de-cartier-642-sa-sunglasses-ct0642sa\/#primaryimage","url":"https:\/\/andreopticas.com\/wp-content\/uploads\/2026\/02\/33244890_64898920_1000.png","contentUrl":"https:\/\/andreopticas.com\/wp-content\/uploads\/2026\/02\/33244890_64898920_1000.png","width":1000,"height":1334,"caption":"Cartier C de Cartier 642\/SA Sunglasses - CT0642SA Gold - CT0642SA"},{"@type":"BreadcrumbList","@id":"https:\/\/andreopticas.com\/product\/c-de-cartier-642-sa-sunglasses-ct0642sa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/andreopticas.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/andreopticas.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Cartier","item":"https:\/\/andreopticas.com\/brand\/cartier\/"},{"@type":"ListItem","position":4,"name":"C de Cartier 642\/SA Sunglasses &#8211; CT0642SA"}]},{"@type":"WebSite","@id":"https:\/\/andreopticas.com\/#website","url":"https:\/\/andreopticas.com\/","name":"Andr\u00e9 Opticas","description":"","publisher":{"@id":"https:\/\/andreopticas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andreopticas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/andreopticas.com\/#organization","name":"Andr\u00e9 Opticas","alternateName":"Pl\u00ednio Leal & Ana Leal, Lda","url":"https:\/\/andreopticas.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/andreopticas.com\/#\/schema\/logo\/image\/","url":"https:\/\/andreopticas.com\/wp-content\/uploads\/2024\/11\/AO-logo-horizontal-pantone.svg","contentUrl":"https:\/\/andreopticas.com\/wp-content\/uploads\/2024\/11\/AO-logo-horizontal-pantone.svg","width":797,"height":141,"caption":"Andr\u00e9 Opticas"},"image":{"@id":"https:\/\/andreopticas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/andre.opticas","https:\/\/x.com\/andreopticas","https:\/\/www.instagram.com\/andreopticas","https:\/\/pt.pinterest.com\/andre_opticas\/","https:\/\/www.youtube.com\/@andre.opticas","https:\/\/www.wikidata.org\/wiki\/Q139916977"],"description":"De Vision\u00e1rios para Vision\u00e1rios - H\u00e1 mais de 40 anos. Fundada em 1981, a Andr\u00e9 \u00d3ticas cedo se distinguiu das restantes, tanto pelas cole\u00e7\u00f5es exclusivas e distintas que trouxe para Portugal, como pela aten\u00e7\u00e3o e cuidado que dedica aos seus clientes. A Andr\u00e9 \u00d3ticas \u00e9 hoje uma marca portuguesa de excel\u00eancia, de renome, inovadora e diferenciadora no servi\u00e7o ao cliente.","email":"ao@andreopticas.com","telephone":"+351 916 368 052"}]},"product_brand":"Cartier","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"CT0642SA","product_condition":"new"},"brands":[{"id":383,"slug":"cartier","name":"Cartier"}],"materials":[{"id":377,"slug":"metal","name":"Metal"}],"_links":{"self":[{"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/product\/65078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/media\/65083"}],"wp:attachment":[{"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/media?parent=65078"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wc\/v3\/brand?post=65078"},{"taxonomy":"face-shape","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/face-shape?post=65078"},{"taxonomy":"frame-shape","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/frame-shape?post=65078"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/gender?post=65078"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/material?post=65078"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/product_brand?post=65078"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/product_cat?post=65078"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/product_tag?post=65078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}