{"id":17045,"date":"2025-02-24T17:44:04","date_gmt":"2025-02-24T17:44:04","guid":{"rendered":"https:\/\/ao.ad-pulse.com\/product\/10s-vintage-sunglasses\/"},"modified":"2026-07-15T07:39:40","modified_gmt":"2026-07-15T07:39:40","slug":"10s-vintage-sunglasses","status":"publish","type":"product","link":"https:\/\/andreopticas.com\/pt\/product\/10s-vintage-sunglasses\/","title":{"rendered":"\u00d3culos de Sol Vintage 10S"},"content":{"rendered":"<style type=\"text\/css\"><!--\ntd {border: 1px solid #ccc;}br {mso-data-placement:same-cell;}\n--><\/style>\n<p><span>Este modelo \u00e9 \"New Old Stock\" (novo a estrear e nunca usado). Um verdadeiro item de colecionador trazido do passado, totalmente recondicionado e restaurado apenas para si. Possibilidade de adapta\u00e7\u00e3o de lentes graduadas e de sol. Estojo original n\u00e3o dispon\u00edvel. Estamos constantemente a desenterrar novos modelos e designs, e curamos com orgulho um enorme arquivo de eyewear VINTAGE.<\/span><\/p>\n<p><span><br \/><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>This model is a New Old Stock that has never been worn. A true collectors item brought from the past totally refurbished and reconditioned just for you. Possible to fit prescription and sunlenses. Original case not available. We are constantly digging new models and designs and we proudly curate a huge archive of VINTAGE eyewear [&hellip;]<\/p>\n","protected":false},"featured_media":17044,"template":"","meta":{"_acf_changed":false},"brand":[474],"face-shape":[215,214,213,216],"frame-shape":[1724],"gender":[{"id":371,"slug":"men","name":"Homem"},{"id":372,"slug":"mulheres","name":"Mulher"}],"material":[374,377],"product_brand":[],"product_cat":[20,23],"product_tag":[],"class_list":{"0":"post-17045","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"brand-gianfranco-ferre","7":"face-shape-diamond-face","8":"face-shape-heart-shaped-face","9":"face-shape-oval-face","10":"face-shape-square-face","11":"frame-shape-oval","12":"gender-men","13":"gender-women","14":"material-acetate","15":"material-metal","16":"product_cat-sunglasses","17":"product_cat-vintage","19":"first","20":"instock","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-variable","25":"has-default-attributes","26":"wvs-archive-product-wrapper","27":"rtwpvg-product"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v26.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gianfranco Ferre 10S Vintage Sunglasses | Andr\u00e9 Opticas<\/title>\n<meta name=\"description\" content=\"In stock and ready to ship worldwide. Discover our exclusive curated selection of Gianfranco Ferre glasses, frames, sunglasses, vintage frames and vintage sunglasses at our online store.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andreopticas.com\/pt\/produto\/10s-vintage-sunglasses\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gianfranco Ferre 10S Vintage Sunglasses\" \/>\n<meta property=\"og:description\" content=\"In stock and ready to ship worldwide. Discover our exclusive curated selection of Gianfranco Ferre glasses, frames, sunglasses, vintage frames and vintage sunglasses at our online store.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andreopticas.com\/pt\/produto\/10s-vintage-sunglasses\/\" \/>\n<meta property=\"og:site_name\" content=\"Andr\u00e9 Opticas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/andre.opticas\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T07:39:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/andreopticas.com\/wp-content\/uploads\/2025\/02\/0101100900006_v1_b98e536b-897d-4371-8ddb-6321a568a05a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@andreopticas\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilidade\" \/>\n\t<meta name=\"twitter:data1\" content=\"Em stock\" \/>\n<meta property=\"product:brand\" content=\"Gianfranco Ferre\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"10S\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gianfranco Ferre 10S Vintage Sunglasses | Andr\u00e9 Opticas","description":"In stock and ready to ship worldwide. Discover our exclusive curated selection of Gianfranco Ferre glasses, frames, sunglasses, vintage frames and vintage sunglasses at our online store.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andreopticas.com\/pt\/produto\/10s-vintage-sunglasses\/","og_locale":"pt_PT","og_type":"article","og_title":"Gianfranco Ferre 10S Vintage Sunglasses","og_description":"In stock and ready to ship worldwide. Discover our exclusive curated selection of Gianfranco Ferre glasses, frames, sunglasses, vintage frames and vintage sunglasses at our online store.","og_url":"https:\/\/andreopticas.com\/pt\/produto\/10s-vintage-sunglasses\/","og_site_name":"Andr\u00e9 Opticas","article_publisher":"https:\/\/www.facebook.com\/andre.opticas","article_modified_time":"2026-07-15T07:39:40+00:00","og_image":[{"width":1000,"height":1334,"url":"https:\/\/andreopticas.com\/wp-content\/uploads\/2025\/02\/0101100900006_v1_b98e536b-897d-4371-8ddb-6321a568a05a.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@andreopticas","twitter_misc":{"Disponibilidade":"Em stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/andreopticas.com\/product\/10s-vintage-sunglasses\/","url":"https:\/\/andreopticas.com\/product\/10s-vintage-sunglasses\/","name":"Gianfranco Ferre 10S Vintage Sunglasses | Andr\u00e9 Opticas","isPartOf":{"@id":"https:\/\/andreopticas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/andreopticas.com\/product\/10s-vintage-sunglasses\/#primaryimage"},"image":{"@id":"https:\/\/andreopticas.com\/product\/10s-vintage-sunglasses\/#primaryimage"},"thumbnailUrl":"https:\/\/andreopticas.com\/wp-content\/uploads\/2025\/02\/0101100900006_v1_b98e536b-897d-4371-8ddb-6321a568a05a.jpg","datePublished":"2025-02-24T17:44:04+00:00","dateModified":"2026-07-15T07:39:40+00:00","description":"In stock and ready to ship worldwide. Discover our exclusive curated selection of Gianfranco Ferre glasses, frames, sunglasses, vintage frames and vintage sunglasses at our online store.","breadcrumb":{"@id":"https:\/\/andreopticas.com\/product\/10s-vintage-sunglasses\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/andreopticas.com\/product\/10s-vintage-sunglasses\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/andreopticas.com\/product\/10s-vintage-sunglasses\/#primaryimage","url":"https:\/\/andreopticas.com\/wp-content\/uploads\/2025\/02\/0101100900006_v1_b98e536b-897d-4371-8ddb-6321a568a05a.jpg","contentUrl":"https:\/\/andreopticas.com\/wp-content\/uploads\/2025\/02\/0101100900006_v1_b98e536b-897d-4371-8ddb-6321a568a05a.jpg","width":1000,"height":1334,"caption":"Gianfranco Ferre 10S Vintage Sunglasses Havana - 10S"},{"@type":"BreadcrumbList","@id":"https:\/\/andreopticas.com\/product\/10s-vintage-sunglasses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/andreopticas.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/andreopticas.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Gianfranco Ferre","item":"https:\/\/andreopticas.com\/brand\/gianfranco-ferre\/"},{"@type":"ListItem","position":4,"name":"10S Vintage Sunglasses"}]},{"@type":"WebSite","@id":"https:\/\/andreopticas.com\/#website","url":"https:\/\/andreopticas.com\/","name":"Andr\u00e9 Opticas","description":"","publisher":{"@id":"https:\/\/andreopticas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andreopticas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/andreopticas.com\/#organization","name":"Andr\u00e9 Opticas","alternateName":"Pl\u00ednio Leal & Ana Leal, Lda","url":"https:\/\/andreopticas.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/andreopticas.com\/#\/schema\/logo\/image\/","url":"https:\/\/andreopticas.com\/wp-content\/uploads\/2024\/11\/AO-logo-horizontal-pantone.svg","contentUrl":"https:\/\/andreopticas.com\/wp-content\/uploads\/2024\/11\/AO-logo-horizontal-pantone.svg","width":797,"height":141,"caption":"Andr\u00e9 Opticas"},"image":{"@id":"https:\/\/andreopticas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/andre.opticas","https:\/\/x.com\/andreopticas","https:\/\/www.instagram.com\/andreopticas","https:\/\/pt.pinterest.com\/andre_opticas\/","https:\/\/www.youtube.com\/@andre.opticas","https:\/\/www.wikidata.org\/wiki\/Q139916977"],"description":"De Vision\u00e1rios para Vision\u00e1rios - H\u00e1 mais de 40 anos. Fundada em 1981, a Andr\u00e9 \u00d3ticas cedo se distinguiu das restantes, tanto pelas cole\u00e7\u00f5es exclusivas e distintas que trouxe para Portugal, como pela aten\u00e7\u00e3o e cuidado que dedica aos seus clientes. A Andr\u00e9 \u00d3ticas \u00e9 hoje uma marca portuguesa de excel\u00eancia, de renome, inovadora e diferenciadora no servi\u00e7o ao cliente.","email":"ao@andreopticas.com","telephone":"+351 916 368 052"}]},"product_brand":"Gianfranco Ferre","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"10S","product_condition":"new"},"brands":[{"id":474,"slug":"gianfranco-ferre","name":"Gianfranco Ferre"}],"materials":[{"id":374,"slug":"acetate","name":"Acetato"},{"id":377,"slug":"metal","name":"Metal"}],"_links":{"self":[{"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/product\/17045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/media\/17044"}],"wp:attachment":[{"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/media?parent=17045"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wc\/v3\/brand?post=17045"},{"taxonomy":"face-shape","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/face-shape?post=17045"},{"taxonomy":"frame-shape","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/frame-shape?post=17045"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/gender?post=17045"},{"taxonomy":"material","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/material?post=17045"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/product_brand?post=17045"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/product_cat?post=17045"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/andreopticas.com\/pt\/wp-json\/wp\/v2\/product_tag?post=17045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}